 {"id":1619,"date":"2021-02-16T11:29:14","date_gmt":"2021-02-16T11:29:14","guid":{"rendered":"http:\/\/www.bbe.es\/?page_id=1619"},"modified":"2021-04-15T12:11:11","modified_gmt":"2021-04-15T12:11:11","slug":"inicio","status":"publish","type":"page","link":"https:\/\/www.bbe.es\/en\/","title":{"rendered":"Inicio"},"content":{"rendered":"<section class=\"flexslider kenburns2 full-height\">\n\t<ul class=\"slides\">\n\t\t\t\n\t\t\t<li class=\"bg-dark bg-dark-30\">\n\n\t\t\t\t\n\t\t\t\t<div class=\"slide-background\" data-sizes-background='[{\"width\":150,\"url\":\"https:\\\/\\\/www.bbe.es\\\/assets\\\/media\\\/slide1-1-150x78.jpg\"},{\"width\":300,\"url\":\"https:\\\/\\\/www.bbe.es\\\/assets\\\/media\\\/slide1-1-300x156.jpg\"},{\"width\":400,\"url\":\"https:\\\/\\\/www.bbe.es\\\/assets\\\/media\\\/slide1-1-400x208.jpg\"},{\"width\":480,\"url\":\"https:\\\/\\\/www.bbe.es\\\/assets\\\/media\\\/slide1-1-480x250.jpg\"},{\"width\":550,\"url\":\"https:\\\/\\\/www.bbe.es\\\/assets\\\/media\\\/slide1-1-550x286.jpg\"},{\"width\":768,\"url\":\"https:\\\/\\\/www.bbe.es\\\/assets\\\/media\\\/slide1-1-768x400.jpg\"},{\"width\":992,\"url\":\"https:\\\/\\\/www.bbe.es\\\/assets\\\/media\\\/slide1-1-992x517.jpg\"},{\"width\":1200,\"url\":\"https:\\\/\\\/www.bbe.es\\\/assets\\\/media\\\/slide1-1-1200x625.jpg\"},{\"width\":1920,\"url\":\"https:\\\/\\\/www.bbe.es\\\/assets\\\/media\\\/slide1-1.jpg\"}]' data-jarallax-video=\"\"><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"container\">\n\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t<article class=\"d-flex align-items-center flex-column\">\n\t\t\t\t\t\t\t<div class=\"col-md-8 text-center\">\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"h1 m-b-20\">\n\t\t\t\t\t\t\t\t\t\tBBE, An efficient design\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"m-b-40\">\n\t\t\t\t\t\t\t\t\t\tThe combined-cycle of natural gas and steam generates an efficiency of more than 56%.\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"btn btn-circle btn-lg btn-brand\" href=\"http:\/\/www.bbe.es\/en\/technical-description\/introduction\/\">\n\t\t\t\t\t\t\t\t\tMORE INFORMATION\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/article>\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/li>\n\t\t\t\n\t\t\t<li class=\"bg-dark bg-dark-30\">\n\n\t\t\t\t\n\t\t\t\t<div class=\"slide-background\" data-sizes-background='[{\"width\":150,\"url\":\"https:\\\/\\\/www.bbe.es\\\/assets\\\/media\\\/slide-BBE-150x100.jpg\"},{\"width\":300,\"url\":\"https:\\\/\\\/www.bbe.es\\\/assets\\\/media\\\/slide-BBE-300x201.jpg\"},{\"width\":400,\"url\":\"https:\\\/\\\/www.bbe.es\\\/assets\\\/media\\\/slide-BBE-400x268.jpg\"},{\"width\":480,\"url\":\"https:\\\/\\\/www.bbe.es\\\/assets\\\/media\\\/slide-BBE-480x321.jpg\"},{\"width\":550,\"url\":\"https:\\\/\\\/www.bbe.es\\\/assets\\\/media\\\/slide-BBE-550x368.jpg\"},{\"width\":768,\"url\":\"https:\\\/\\\/www.bbe.es\\\/assets\\\/media\\\/slide-BBE-768x514.jpg\"},{\"width\":992,\"url\":\"https:\\\/\\\/www.bbe.es\\\/assets\\\/media\\\/slide-BBE-992x664.jpg\"},{\"width\":1200,\"url\":\"https:\\\/\\\/www.bbe.es\\\/assets\\\/media\\\/slide-BBE-1200x804.jpg\"},{\"width\":1650,\"url\":\"https:\\\/\\\/www.bbe.es\\\/assets\\\/media\\\/slide-BBE.jpg\"}]' data-jarallax-video=\"\"><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"container\">\n\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t<article class=\"d-flex align-items-center flex-column\">\n\t\t\t\t\t\t\t<div class=\"col-md-8 text-center\">\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"h1 m-b-20\">\n\t\t\t\t\t\t\t\t\t\tQuality, safety and environment\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"btn btn-circle btn-lg btn-brand\" href=\"http:\/\/www.bbe.es\/en\/ssmaq-markets\/quality-healt-safety\/quality-healt-safety\/\">\n\t\t\t\t\t\t\t\t\tMORE INFORMATION\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/article>\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/li>\n\t\t\t\t\t\t\n\t<\/ul>\n<\/section>\r\n<section class=\"module\">\r\n\t<div class=\"container\">\r\n\t\t<div class=\"row blog-magazine\">\r\n\t\t\t<div class=\"col-lg-6\">\r\n\t\t\t\t<!-- Post-->\r\n\t\t\t\t<article class=\"post\">\r\n\t\t\t\t\t<div class=\"post-background\" data-background=\"https:\/\/www.bbe.es\/assets\/media\/portada-visita-bbe.jpg\">\r\n\t\t\t\t\t\t<div class=\"post-header text-shadow\">\r\n\t\t\t\t\t\t\t<h2 class=\"post-title \">\r\n\t\t\t\t\t\t\t\t<a href=\"\/en\/virtual-visit\/\">Virtual Visit<\/a>\r\n\t\t\t\t\t\t\t<\/h2>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<a class=\"post-background-link\" href=\"\/en\/virtual-visit\/\"><\/a>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/article>\r\n\t\t\t\t<!-- Post end-->\r\n\t\t\t<\/div>\r\n\t\t\t<div class=\"col-lg-6\">\r\n\t\t\t\t<!-- Post-->\r\n\t\t\t\t<article class=\"post\">\r\n\t\t\t\t\t<div class=\"post-background\" data-background=\"http:\/\/www.bbe.es\/assets\/media\/banner3-1.jpg\">\r\n\t\t\t\t\t\t<div class=\"post-header text-shadow\">\r\n\t\t\t\t\t\t\t<h2 class=\"post-title\">\r\n\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.bbe.es\/en\/ssmaq-markets\/quality-healt-safety\/quality-healt-safety\/\">Management systems<\/a>\r\n\t\t\t\t\t\t\t<\/h2>\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<a class=\"post-background-link\" href=\"http:\/\/www.bbe.es\/en\/ssmaq-markets\/quality-healt-safety\/quality-healt-safety\/\"><\/a>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/article>\r\n\t\t\t\t<!-- Post end-->\r\n\t\t\t<\/div>\r\n\r\n\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/section>\r\n<section class=\"module bg-light p-b-0\">\r\n\t<div class=\"container\">\r\n\t\t<div class=\"row\">\r\n\t\t\t<div class=\"col-md-10 m-auto\">\r\n\t\t\t\t<div class=\"text-center module-title\">\r\n\t\t\t\t\t<h2>Plant Overview<\/h2>\r\n\t\t\t\t\t<p class=\"p-t-20\">BBE\u2019s Combined Cycle Power Plant is located on a plot of land of approximately five hectares, situated on the excavated site at Punta Lucero for the extension of the port of Bilbao.<\/p>\r\n\t\t\t\t    <div class=\"titular\"><h3>Do you want to know it?<\/h3><\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/section>\r\n<!-- Categorias-->\r\n\t\t\t\t<section class=\"module p-0\">\r\n\t\t\t\t\t<div class=\"container-fluid\">\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"row row-portfolio\" date-portfolio-type=\"standard\" data-columns=\"3\">\r\n\t\t\t\t\t\t\t<div class=\"grid-sizer\"><\/div>\r\n\t\t\t\t\t\t\t<div class=\"portfolio-item\">\r\n\t\t\t\t\t\t\t\t<div class=\"portfolio-wrapper\">\r\n\t\t\t\t\t\t\t\t\t<img alt=\"\" width=\"1100\" height=\"700\" class=\"lazyload\" data-src=\"http:\/\/www.bbe.es\/assets\/media\/descripcion-general-planta-01-1100x700-1.jpg\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-overlay\"><\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"portfolio-caption\">\r\n\t\t\t\t\t\t\t\t\t<h5 class=\"portfolio-title\">Plant Overview<\/h5>\r\n\t\t\t\t\t\t\t\t<\/div><a class=\"portfolio-link\" href=\"http:\/\/www.bbe.es\/en\/technical-description\/introduction\/\"><\/a>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"portfolio-item\">\r\n\t\t\t\t\t\t\t\t<div class=\"portfolio-wrapper\">\r\n\t\t\t\t\t\t\t\t\t<img alt=\"\" width=\"1100\" height=\"700\" class=\"lazyload\" data-src=\"http:\/\/www.bbe.es\/assets\/media\/descripcion-general-planta-02-1100x700-1.jpg\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-overlay\"><\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"portfolio-caption\">\r\n\t\t\t\t\t\t\t\t\t<h5 class=\"portfolio-title\">Heat cycle<\/h5>\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div><a class=\"portfolio-link\" href=\"http:\/\/www.bbe.es\/en\/technical-description\/heat-cycle\/\"><\/a>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"portfolio-item\">\r\n\t\t\t\t\t\t\t\t<div class=\"portfolio-wrapper\">\r\n\t\t\t\t\t\t\t\t\t<img alt=\"\" width=\"1100\" height=\"700\" class=\"lazyload\" data-src=\"http:\/\/www.bbe.es\/assets\/media\/descripcion-general-planta-03-1100x700-1.jpg\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-overlay\"><\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"portfolio-caption\">\r\n\t\t\t\t\t\t\t\t\t<h5 class=\"portfolio-title\">AUXILIARY SYSTEMS<\/h5>\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div><a class=\"portfolio-link\" href=\"http:\/\/www.bbe.es\/en\/technical-description\/auxiliary-systems\/\"><\/a>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"portfolio-item\">\r\n\t\t\t\t\t\t\t\t<div class=\"portfolio-wrapper\">\r\n\t\t\t\t\t\t\t\t\t<img alt=\"\" width=\"1100\" height=\"700\" class=\"lazyload\" data-src=\"http:\/\/www.bbe.es\/assets\/media\/descripcion-general-planta-04-1100x700-1.jpg\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-overlay\"><\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"portfolio-caption\">\r\n\t\t\t\t\t\t\t\t\t<h5 class=\"portfolio-title\">ELECTRICAL SYSTEM<\/h5>\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div><a class=\"portfolio-link\" href=\"http:\/\/www.bbe.es\/en\/technical-description\/electrical-system\/\"><\/a>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"portfolio-item\">\r\n\t\t\t\t\t\t\t\t<div class=\"portfolio-wrapper\">\r\n\t\t\t\t\t\t\t\t\t<img alt=\"\" width=\"1100\" height=\"700\" class=\"lazyload\" data-src=\"http:\/\/www.bbe.es\/assets\/media\/descripcion-general-planta-05-1100x700-1.jpg\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-overlay\"><\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"portfolio-caption\">\r\n\t\t\t\t\t\t\t\t\t<h5 class=\"portfolio-title\">SUPERVISION AND CONTROL SYSTEM<\/h5>\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div><a class=\"portfolio-link\" href=\"http:\/\/www.bbe.es\/en\/technical-description\/supervision-and-control-system\/\"><\/a>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"portfolio-item\">\r\n\t\t\t\t\t\t\t\t<div class=\"portfolio-wrapper\">\r\n\t\t\t\t\t\t\t<img alt=\"\" width=\"1100\" height=\"700\" class=\"lazyload\" data-src=\"http:\/\/www.bbe.es\/assets\/media\/descripcion-general-planta-06-1100x700-2-1.jpg\">\t\t\r\n\r\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-overlay\"><\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"portfolio-caption\">\r\n\t\t\t\t\t\t\t\t\t<h5 class=\"portfolio-title\">AREAS OF DE POWER STATION<\/h5>\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t<\/div><a class=\"portfolio-link\" href=\"http:\/\/www.bbe.es\/en\/technical-description\/areas-of-de-power-station\/\"><\/a>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/section>\r\n\t\t\t\t<!-- Categorias end-->\r\n<!--[_e_template_part_content name=\"template-parts\/content-ultimas-noticias\"]\r\n[_e_page_content id=\"2119\"]-->","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1619","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.bbe.es\/en\/wp-json\/wp\/v2\/pages\/1619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bbe.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bbe.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bbe.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bbe.es\/en\/wp-json\/wp\/v2\/comments?post=1619"}],"version-history":[{"count":6,"href":"https:\/\/www.bbe.es\/en\/wp-json\/wp\/v2\/pages\/1619\/revisions"}],"predecessor-version":[{"id":2491,"href":"https:\/\/www.bbe.es\/en\/wp-json\/wp\/v2\/pages\/1619\/revisions\/2491"}],"wp:attachment":[{"href":"https:\/\/www.bbe.es\/en\/wp-json\/wp\/v2\/media?parent=1619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}